{"id":21184,"date":"2025-07-06T17:15:16","date_gmt":"2025-07-06T20:15:16","guid":{"rendered":"https:\/\/augustobaffa.pro.br\/site\/?p=21184"},"modified":"2025-07-06T17:15:25","modified_gmt":"2025-07-06T20:15:25","slug":"desafio-dos-drones-partida-realizada-em-06-07-2025-1715-2","status":"publish","type":"post","link":"https:\/\/augustobaffa.pro.br\/site\/2025\/07\/desafio-dos-drones-partida-realizada-em-06-07-2025-1715-2\/","title":{"rendered":"Desafio dos Drones: Partida Realizada em 06\/07\/2025 17:15"},"content":{"rendered":"<p><a href=\"\/\/augustobaffa.pro.br\/site\/inf1771-inteligencia-artificial-desafio-dos-drones\/\">Descri\u00e7\u00e3o do jogo e Devkits<\/a><\/p>\n<p>Resultados para a partida do Desafio dos Drones realizada em 06\/07\/2025 17:15.<\/p>\n<table align=\"center\" width=\"80%\">\n<tr>\n<th>Player Name<\/th>\n<th>Energy<\/th>\n<th>Score<\/th>\n<\/tr>\n<tr>\n<td align=\"center\">Baffa Bot 5<\/td>\n<td align=\"center\">100<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Baffa Bot 2<\/td>\n<td align=\"center\">100<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Baffa Bot 3<\/td>\n<td align=\"center\">100<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Baffa Bot 1<\/td>\n<td align=\"center\">100<\/td>\n<td align=\"center\">-2<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Baffa Bot 4<\/td>\n<td align=\"center\">100<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Um Dia de Furia<\/td>\n<td align=\"center\">100<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Um Dia de Furia<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">h4thr0_example<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Um Dia de Furia<\/td>\n<td align=\"center\">100<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">h4thr0_example<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Bot FAF<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Um Dia de Furia<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">(observing)<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Um Dia de Furia<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Bot FAF<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">h4thr0_example<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">h4thr0_example<\/td>\n<td align=\"center\">100<\/td>\n<td align=\"center\">-76<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Athena<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">Athena<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">zvz (observing)<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">testesM<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<tr>\n<td align=\"center\">testesM<\/td>\n<td align=\"center\">0<\/td>\n<td align=\"center\">0<\/td>\n<\/tr>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Descri\u00e7\u00e3o do jogo e Devkits Resultados para a partida do Desafio dos Drones realizada em 06\/07\/2025 17:15. Player Name Energy Score Baffa Bot 5 100 0 Baffa Bot 2 100 0 Baffa Bot 3 100 0 Baffa Bot 1 100 -2 Baffa Bot 4 100 0 Um Dia de Furia 100 0 Um Dia de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[13],"tags":[],"class_list":["post-21184","post","type-post","status-publish","format-standard","hentry","category-desafio-drones"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p45Kmr-5vG","jetpack-related-posts":[],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/augustobaffa.pro.br\/site\/wp-json\/wp\/v2\/posts\/21184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/augustobaffa.pro.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/augustobaffa.pro.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/augustobaffa.pro.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/augustobaffa.pro.br\/site\/wp-json\/wp\/v2\/comments?post=21184"}],"version-history":[{"count":1,"href":"https:\/\/augustobaffa.pro.br\/site\/wp-json\/wp\/v2\/posts\/21184\/revisions"}],"predecessor-version":[{"id":21185,"href":"https:\/\/augustobaffa.pro.br\/site\/wp-json\/wp\/v2\/posts\/21184\/revisions\/21185"}],"wp:attachment":[{"href":"https:\/\/augustobaffa.pro.br\/site\/wp-json\/wp\/v2\/media?parent=21184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/augustobaffa.pro.br\/site\/wp-json\/wp\/v2\/categories?post=21184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/augustobaffa.pro.br\/site\/wp-json\/wp\/v2\/tags?post=21184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}